{"id":646,"date":"2019-01-08T11:11:35","date_gmt":"2019-01-08T10:11:35","guid":{"rendered":"https:\/\/www.unserekurve.de\/blog\/?p=646"},"modified":"2020-04-26T19:16:38","modified_gmt":"2020-04-26T17:16:38","slug":"erste-ergebnisse-der-umfrage-zum-umgang-mit-sexismus-sexualisierter-belaestigung-und-gewalt-im-kontext-fussball-und-damit-verbundene-herausforderungen-fuer-das-netzwerk-fussball","status":"publish","type":"post","link":"https:\/\/www.unserekurve.de\/blog\/erste-ergebnisse-der-umfrage-zum-umgang-mit-sexismus-sexualisierter-belaestigung-und-gewalt-im-kontext-fussball-und-damit-verbundene-herausforderungen-fuer-das-netzwerk-fussball\/","title":{"rendered":"Umfrage zu sexualisierter Gewalt im Fu\u00dfball liefert erste Ergebnisse"},"content":{"rendered":"\r\n\r\n\r\n<p>Erste Ergebnisse der Umfrage \u201eZum Umgang mit Sexismus, sexualisierter Bel\u00e4stigung und Gewalt im Kontext Fu\u00dfball\u201c und damit verbundene Herausforderungen f\u00fcr das Netzwerk Fu\u00dfball<\/p>\r\n<p>Sexismus, sexualisierte Bel\u00e4stigung und Gewalt sind ein gesamtgesellschaftliches Problem, mit dem ebenso \u201eder Fu\u00dfball\u201c konfrontiert ist. In der breiten \u00d6ffentlichkeit wird dies z.B. durch sexistische Spruchb\u00e4nder, aber auch durch besonders gravierende Vorf\u00e4lle, wie einer Vergewaltigung in einem Sonderzug, sichtbar. Doch auch systematische Ausschl\u00fcsse aufgrund des Geschlechts, herabw\u00fcrdigende \u00c4u\u00dferungen oder vermeintlich \u201egut\u201c gemeinte Aktionen des Vereins finden sich in und um die Stadien wieder.\u00a0<\/p>\r\n\r\n\r\n\r\n<p>Um in Erfahrung zu bringen, wie die verschiedenen Akteure in den Stadien \u2013 Vereine, Fanprojekte und Fangruppen \u2013 mit diesen Problemen umgehen und welchen Handlungsbedarf sie sehen, haben die Fanorganisation \u201eUnsere Kurve\u201c, das Netzwerk \u201eF_in &#8211; Frauen im Fu\u00dfball\u201c und die \u201eBundesarbeitsgemeinschaft der Fanprojekte\u201c im Sommer eine Online-Umfrage unter den verschiedenen Akteuren im Fu\u00dfball initiiert.\u00a0<\/p>\r\n\r\n\r\n\r\n<p>Mehr als 130 Antworten von Fangruppierungen, Fanprojekten und offiziellen Stellen aus \u00fcber 30 Vereinen \u2013 von Bundesliga bis Regionalliga \u2013 haben uns erreicht. Dadurch wird bereits deutlich, wie gro\u00df der Bedarf ist, sich zu dem Thema zu \u00e4u\u00dfern.\u00a0Ziel der Umfrage ist es, eine \u00dcbersicht zum aktuellen Bedarf, zu Positionierungen und gew\u00fcnschten Handlungsformen zu entwickeln.\u00a0Unter dem unterstehenden Link kann das PDF mit den ersten Ergebnissen der Umfrage eingesehen werden.<\/p>\r\n\r\n\r\n\r\n<p>Zentrale Ergebnisse \u2013 sowohl von Vereinen, Fanprojekten und Fangruppen benannt \u2013 sind die dringende<\/p>\r\n\r\n\r\n\r\n<ul class=\"wp-block-list\">\r\n<li>\u00dcbernahme von Verantwortung f\u00fcr Schutz und Sicherheit der Zuschauer*innen durch Vereine und Verb\u00e4nde;<\/li>\r\n<li>Sensibilisierung und Schulung von Ordner*innen und anderen Ansprechpersonen in und um die Stadien;<\/li>\r\n<li>Initiierung einer lokalen und bundesweiten Vernetzung im Umgang mit Sexismus, sexualisierter Bel\u00e4stigung und Gewalt;\u00a0<\/li>\r\n<li>Notwendigkeit der Entwicklung von exemplarischen Handlungskonzepten f\u00fcr alle Beteiligten.<\/li>\r\n<\/ul>\r\n\r\n\r\n\r\n<p>Zeitnah werden wir eine institutionen\u00fcbergreifende Arbeitsgruppe zu Sexismus, sexualisierter Bel\u00e4stigung und Gewalt initiieren. Diese wird in Zusammenarbeit mit den Verb\u00e4nden einen Workshop erarbeiten, in dem die Ergebnisse der Umfrage detailliert vorgestellt werden und eine inhaltliche Weiterarbeit garantiert wird.\u00a0<\/p>\r\n\r\n\r\n\r\n<p>F\u00fcr weiterf\u00fchrende Fragen stehen wir gerne zur Verf\u00fcgung.<\/p>\r\n\r\n\r\n\r\n<p>Unsere Kurve, F_in \u2013 Frauen im Fu\u00dfball, Bundesarbeitsgemeinschaft der Fanprojekte<\/p>\r\n\r\n\r\n\r\n<p>PDF mit den ersten Ergebnissen der Studie =&gt; <a href=\"https:\/\/www.unserekurve.de\/blog\/wp-content\/uploads\/Erste_Ergebnisse_zur_Onlineumfrage_zu_Sexismus_und_sexualisierter_Gewalt_im_Kontext_Fu\u00dfball.pdf\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (\u00f6ffnet in neuem Tab)\">https:\/\/www.unserekurve.de\/blog\/wp-content\/uploads\/Erste_Ergebnisse_zur_Onlineumfrage_zu_Sexismus_und_sexualisierter_Gewalt_im_Kontext_Fu\u00dfball.pdf<\/a><\/p>\r\n<p><em>Foto: Arne Amberg<\/em><\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>Erste Ergebnisse der Umfrage \u201eZum Umgang mit Sexismus, sexualisierter Bel\u00e4stigung und Gewalt im Kontext Fu\u00dfball\u201c und damit verbundene Herausforderungen f\u00fcr das Netzwerk Fu\u00dfball Sexismus, sexualisierte Bel\u00e4stigung und Gewalt sind ein gesamtgesellschaftliches Problem, mit dem ebenso \u201eder Fu\u00dfball\u201c konfrontiert ist. In der breiten \u00d6ffentlichkeit wird dies z.B. durch sexistische Spruchb\u00e4nder, aber auch durch besonders gravierende Vorf\u00e4lle,&#8230;<\/p>\n","protected":false},"author":4,"featured_media":999,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-646","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuelles"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Umfrage zu sexualisierter Gewalt im Fu\u00dfball liefert erste Ergebnisse &#8226; Unsere Kurve<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.unserekurve.de\/blog\/erste-ergebnisse-der-umfrage-zum-umgang-mit-sexismus-sexualisierter-belaestigung-und-gewalt-im-kontext-fussball-und-damit-verbundene-herausforderungen-fuer-das-netzwerk-fussball\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Umfrage zu sexualisierter Gewalt im Fu\u00dfball liefert erste Ergebnisse &#8226; Unsere Kurve\" \/>\n<meta property=\"og:description\" content=\"Erste Ergebnisse der Umfrage \u201eZum Umgang mit Sexismus, sexualisierter Bel\u00e4stigung und Gewalt im Kontext Fu\u00dfball\u201c und damit verbundene Herausforderungen f\u00fcr das Netzwerk Fu\u00dfball Sexismus, sexualisierte Bel\u00e4stigung und Gewalt sind ein gesamtgesellschaftliches Problem, mit dem ebenso \u201eder Fu\u00dfball\u201c konfrontiert ist. In der breiten \u00d6ffentlichkeit wird dies z.B. durch sexistische Spruchb\u00e4nder, aber auch durch besonders gravierende Vorf\u00e4lle,...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.unserekurve.de\/blog\/erste-ergebnisse-der-umfrage-zum-umgang-mit-sexismus-sexualisierter-belaestigung-und-gewalt-im-kontext-fussball-und-damit-verbundene-herausforderungen-fuer-das-netzwerk-fussball\/\" \/>\n<meta property=\"og:site_name\" content=\"Unsere Kurve\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-08T10:11:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-26T17:16:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.unserekurve.de\/blog\/wp-content\/uploads\/kaputtes-fangnetz.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Robert Pohl\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Robert Pohl\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.unserekurve.de\\\/blog\\\/erste-ergebnisse-der-umfrage-zum-umgang-mit-sexismus-sexualisierter-belaestigung-und-gewalt-im-kontext-fussball-und-damit-verbundene-herausforderungen-fuer-das-netzwerk-fussball\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.unserekurve.de\\\/blog\\\/erste-ergebnisse-der-umfrage-zum-umgang-mit-sexismus-sexualisierter-belaestigung-und-gewalt-im-kontext-fussball-und-damit-verbundene-herausforderungen-fuer-das-netzwerk-fussball\\\/\"},\"author\":{\"name\":\"Robert Pohl\",\"@id\":\"https:\\\/\\\/www.unserekurve.de\\\/blog\\\/#\\\/schema\\\/person\\\/dc7e70ab6b2bb60df11b17fce7ad9704\"},\"headline\":\"Umfrage zu sexualisierter Gewalt im Fu\u00dfball liefert erste Ergebnisse\",\"datePublished\":\"2019-01-08T10:11:35+00:00\",\"dateModified\":\"2020-04-26T17:16:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.unserekurve.de\\\/blog\\\/erste-ergebnisse-der-umfrage-zum-umgang-mit-sexismus-sexualisierter-belaestigung-und-gewalt-im-kontext-fussball-und-damit-verbundene-herausforderungen-fuer-das-netzwerk-fussball\\\/\"},\"wordCount\":394,\"image\":{\"@id\":\"https:\\\/\\\/www.unserekurve.de\\\/blog\\\/erste-ergebnisse-der-umfrage-zum-umgang-mit-sexismus-sexualisierter-belaestigung-und-gewalt-im-kontext-fussball-und-damit-verbundene-herausforderungen-fuer-das-netzwerk-fussball\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.unserekurve.de\\\/blog\\\/wp-content\\\/uploads\\\/kaputtes-fangnetz.jpg\",\"articleSection\":[\"Aktuelles\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.unserekurve.de\\\/blog\\\/erste-ergebnisse-der-umfrage-zum-umgang-mit-sexismus-sexualisierter-belaestigung-und-gewalt-im-kontext-fussball-und-damit-verbundene-herausforderungen-fuer-das-netzwerk-fussball\\\/\",\"url\":\"https:\\\/\\\/www.unserekurve.de\\\/blog\\\/erste-ergebnisse-der-umfrage-zum-umgang-mit-sexismus-sexualisierter-belaestigung-und-gewalt-im-kontext-fussball-und-damit-verbundene-herausforderungen-fuer-das-netzwerk-fussball\\\/\",\"name\":\"Umfrage zu sexualisierter Gewalt im Fu\u00dfball liefert erste Ergebnisse &#8226; Unsere Kurve\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.unserekurve.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.unserekurve.de\\\/blog\\\/erste-ergebnisse-der-umfrage-zum-umgang-mit-sexismus-sexualisierter-belaestigung-und-gewalt-im-kontext-fussball-und-damit-verbundene-herausforderungen-fuer-das-netzwerk-fussball\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.unserekurve.de\\\/blog\\\/erste-ergebnisse-der-umfrage-zum-umgang-mit-sexismus-sexualisierter-belaestigung-und-gewalt-im-kontext-fussball-und-damit-verbundene-herausforderungen-fuer-das-netzwerk-fussball\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.unserekurve.de\\\/blog\\\/wp-content\\\/uploads\\\/kaputtes-fangnetz.jpg\",\"datePublished\":\"2019-01-08T10:11:35+00:00\",\"dateModified\":\"2020-04-26T17:16:38+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.unserekurve.de\\\/blog\\\/#\\\/schema\\\/person\\\/dc7e70ab6b2bb60df11b17fce7ad9704\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.unserekurve.de\\\/blog\\\/erste-ergebnisse-der-umfrage-zum-umgang-mit-sexismus-sexualisierter-belaestigung-und-gewalt-im-kontext-fussball-und-damit-verbundene-herausforderungen-fuer-das-netzwerk-fussball\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.unserekurve.de\\\/blog\\\/erste-ergebnisse-der-umfrage-zum-umgang-mit-sexismus-sexualisierter-belaestigung-und-gewalt-im-kontext-fussball-und-damit-verbundene-herausforderungen-fuer-das-netzwerk-fussball\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.unserekurve.de\\\/blog\\\/erste-ergebnisse-der-umfrage-zum-umgang-mit-sexismus-sexualisierter-belaestigung-und-gewalt-im-kontext-fussball-und-damit-verbundene-herausforderungen-fuer-das-netzwerk-fussball\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.unserekurve.de\\\/blog\\\/wp-content\\\/uploads\\\/kaputtes-fangnetz.jpg\",\"contentUrl\":\"https:\\\/\\\/www.unserekurve.de\\\/blog\\\/wp-content\\\/uploads\\\/kaputtes-fangnetz.jpg\",\"width\":1200,\"height\":533,\"caption\":\"Foto: Arne Amberg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.unserekurve.de\\\/blog\\\/erste-ergebnisse-der-umfrage-zum-umgang-mit-sexismus-sexualisierter-belaestigung-und-gewalt-im-kontext-fussball-und-damit-verbundene-herausforderungen-fuer-das-netzwerk-fussball\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.unserekurve.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Umfrage zu sexualisierter Gewalt im Fu\u00dfball liefert erste Ergebnisse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.unserekurve.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.unserekurve.de\\\/blog\\\/\",\"name\":\"Unsere Kurve\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.unserekurve.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.unserekurve.de\\\/blog\\\/#\\\/schema\\\/person\\\/dc7e70ab6b2bb60df11b17fce7ad9704\",\"name\":\"Robert Pohl\",\"url\":\"https:\\\/\\\/www.unserekurve.de\\\/blog\\\/author\\\/robert\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Umfrage zu sexualisierter Gewalt im Fu\u00dfball liefert erste Ergebnisse &#8226; Unsere Kurve","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.unserekurve.de\/blog\/erste-ergebnisse-der-umfrage-zum-umgang-mit-sexismus-sexualisierter-belaestigung-und-gewalt-im-kontext-fussball-und-damit-verbundene-herausforderungen-fuer-das-netzwerk-fussball\/","og_locale":"de_DE","og_type":"article","og_title":"Umfrage zu sexualisierter Gewalt im Fu\u00dfball liefert erste Ergebnisse &#8226; Unsere Kurve","og_description":"Erste Ergebnisse der Umfrage \u201eZum Umgang mit Sexismus, sexualisierter Bel\u00e4stigung und Gewalt im Kontext Fu\u00dfball\u201c und damit verbundene Herausforderungen f\u00fcr das Netzwerk Fu\u00dfball Sexismus, sexualisierte Bel\u00e4stigung und Gewalt sind ein gesamtgesellschaftliches Problem, mit dem ebenso \u201eder Fu\u00dfball\u201c konfrontiert ist. In der breiten \u00d6ffentlichkeit wird dies z.B. durch sexistische Spruchb\u00e4nder, aber auch durch besonders gravierende Vorf\u00e4lle,...","og_url":"https:\/\/www.unserekurve.de\/blog\/erste-ergebnisse-der-umfrage-zum-umgang-mit-sexismus-sexualisierter-belaestigung-und-gewalt-im-kontext-fussball-und-damit-verbundene-herausforderungen-fuer-das-netzwerk-fussball\/","og_site_name":"Unsere Kurve","article_published_time":"2019-01-08T10:11:35+00:00","article_modified_time":"2020-04-26T17:16:38+00:00","og_image":[{"width":1200,"height":533,"url":"https:\/\/www.unserekurve.de\/blog\/wp-content\/uploads\/kaputtes-fangnetz.jpg","type":"image\/jpeg"}],"author":"Robert Pohl","twitter_misc":{"Verfasst von":"Robert Pohl","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.unserekurve.de\/blog\/erste-ergebnisse-der-umfrage-zum-umgang-mit-sexismus-sexualisierter-belaestigung-und-gewalt-im-kontext-fussball-und-damit-verbundene-herausforderungen-fuer-das-netzwerk-fussball\/#article","isPartOf":{"@id":"https:\/\/www.unserekurve.de\/blog\/erste-ergebnisse-der-umfrage-zum-umgang-mit-sexismus-sexualisierter-belaestigung-und-gewalt-im-kontext-fussball-und-damit-verbundene-herausforderungen-fuer-das-netzwerk-fussball\/"},"author":{"name":"Robert Pohl","@id":"https:\/\/www.unserekurve.de\/blog\/#\/schema\/person\/dc7e70ab6b2bb60df11b17fce7ad9704"},"headline":"Umfrage zu sexualisierter Gewalt im Fu\u00dfball liefert erste Ergebnisse","datePublished":"2019-01-08T10:11:35+00:00","dateModified":"2020-04-26T17:16:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.unserekurve.de\/blog\/erste-ergebnisse-der-umfrage-zum-umgang-mit-sexismus-sexualisierter-belaestigung-und-gewalt-im-kontext-fussball-und-damit-verbundene-herausforderungen-fuer-das-netzwerk-fussball\/"},"wordCount":394,"image":{"@id":"https:\/\/www.unserekurve.de\/blog\/erste-ergebnisse-der-umfrage-zum-umgang-mit-sexismus-sexualisierter-belaestigung-und-gewalt-im-kontext-fussball-und-damit-verbundene-herausforderungen-fuer-das-netzwerk-fussball\/#primaryimage"},"thumbnailUrl":"https:\/\/www.unserekurve.de\/blog\/wp-content\/uploads\/kaputtes-fangnetz.jpg","articleSection":["Aktuelles"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.unserekurve.de\/blog\/erste-ergebnisse-der-umfrage-zum-umgang-mit-sexismus-sexualisierter-belaestigung-und-gewalt-im-kontext-fussball-und-damit-verbundene-herausforderungen-fuer-das-netzwerk-fussball\/","url":"https:\/\/www.unserekurve.de\/blog\/erste-ergebnisse-der-umfrage-zum-umgang-mit-sexismus-sexualisierter-belaestigung-und-gewalt-im-kontext-fussball-und-damit-verbundene-herausforderungen-fuer-das-netzwerk-fussball\/","name":"Umfrage zu sexualisierter Gewalt im Fu\u00dfball liefert erste Ergebnisse &#8226; Unsere Kurve","isPartOf":{"@id":"https:\/\/www.unserekurve.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.unserekurve.de\/blog\/erste-ergebnisse-der-umfrage-zum-umgang-mit-sexismus-sexualisierter-belaestigung-und-gewalt-im-kontext-fussball-und-damit-verbundene-herausforderungen-fuer-das-netzwerk-fussball\/#primaryimage"},"image":{"@id":"https:\/\/www.unserekurve.de\/blog\/erste-ergebnisse-der-umfrage-zum-umgang-mit-sexismus-sexualisierter-belaestigung-und-gewalt-im-kontext-fussball-und-damit-verbundene-herausforderungen-fuer-das-netzwerk-fussball\/#primaryimage"},"thumbnailUrl":"https:\/\/www.unserekurve.de\/blog\/wp-content\/uploads\/kaputtes-fangnetz.jpg","datePublished":"2019-01-08T10:11:35+00:00","dateModified":"2020-04-26T17:16:38+00:00","author":{"@id":"https:\/\/www.unserekurve.de\/blog\/#\/schema\/person\/dc7e70ab6b2bb60df11b17fce7ad9704"},"breadcrumb":{"@id":"https:\/\/www.unserekurve.de\/blog\/erste-ergebnisse-der-umfrage-zum-umgang-mit-sexismus-sexualisierter-belaestigung-und-gewalt-im-kontext-fussball-und-damit-verbundene-herausforderungen-fuer-das-netzwerk-fussball\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.unserekurve.de\/blog\/erste-ergebnisse-der-umfrage-zum-umgang-mit-sexismus-sexualisierter-belaestigung-und-gewalt-im-kontext-fussball-und-damit-verbundene-herausforderungen-fuer-das-netzwerk-fussball\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.unserekurve.de\/blog\/erste-ergebnisse-der-umfrage-zum-umgang-mit-sexismus-sexualisierter-belaestigung-und-gewalt-im-kontext-fussball-und-damit-verbundene-herausforderungen-fuer-das-netzwerk-fussball\/#primaryimage","url":"https:\/\/www.unserekurve.de\/blog\/wp-content\/uploads\/kaputtes-fangnetz.jpg","contentUrl":"https:\/\/www.unserekurve.de\/blog\/wp-content\/uploads\/kaputtes-fangnetz.jpg","width":1200,"height":533,"caption":"Foto: Arne Amberg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.unserekurve.de\/blog\/erste-ergebnisse-der-umfrage-zum-umgang-mit-sexismus-sexualisierter-belaestigung-und-gewalt-im-kontext-fussball-und-damit-verbundene-herausforderungen-fuer-das-netzwerk-fussball\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.unserekurve.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Umfrage zu sexualisierter Gewalt im Fu\u00dfball liefert erste Ergebnisse"}]},{"@type":"WebSite","@id":"https:\/\/www.unserekurve.de\/blog\/#website","url":"https:\/\/www.unserekurve.de\/blog\/","name":"Unsere Kurve","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.unserekurve.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.unserekurve.de\/blog\/#\/schema\/person\/dc7e70ab6b2bb60df11b17fce7ad9704","name":"Robert Pohl","url":"https:\/\/www.unserekurve.de\/blog\/author\/robert\/"}]}},"jetpack_featured_media_url":"https:\/\/www.unserekurve.de\/blog\/wp-content\/uploads\/kaputtes-fangnetz.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.unserekurve.de\/blog\/wp-json\/wp\/v2\/posts\/646","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unserekurve.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.unserekurve.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.unserekurve.de\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unserekurve.de\/blog\/wp-json\/wp\/v2\/comments?post=646"}],"version-history":[{"count":10,"href":"https:\/\/www.unserekurve.de\/blog\/wp-json\/wp\/v2\/posts\/646\/revisions"}],"predecessor-version":[{"id":1097,"href":"https:\/\/www.unserekurve.de\/blog\/wp-json\/wp\/v2\/posts\/646\/revisions\/1097"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.unserekurve.de\/blog\/wp-json\/wp\/v2\/media\/999"}],"wp:attachment":[{"href":"https:\/\/www.unserekurve.de\/blog\/wp-json\/wp\/v2\/media?parent=646"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.unserekurve.de\/blog\/wp-json\/wp\/v2\/categories?post=646"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.unserekurve.de\/blog\/wp-json\/wp\/v2\/tags?post=646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}