{"id":614,"date":"2018-09-18T17:07:02","date_gmt":"2018-09-18T15:07:02","guid":{"rendered":"https:\/\/www.unserekurve.de\/blog\/?p=614"},"modified":"2020-04-26T13:57:48","modified_gmt":"2020-04-26T11:57:48","slug":"rueckblick-auf-die-9-sitzung-der-ag-fankulturen-am-17-09-2018","status":"publish","type":"post","link":"https:\/\/www.unserekurve.de\/blog\/rueckblick-auf-die-9-sitzung-der-ag-fankulturen-am-17-09-2018\/","title":{"rendered":"R\u00fcckblick auf 9. Sitzung der AG Fankulturen"},"content":{"rendered":"<div class=\"page\" title=\"Page 1\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Im Rahmen der 9. Sitzung der AG Fankulturen, die am 17. September 2018 stattgefunden hat, wurden folgende Themen diskutiert:<\/p>\n<ul>\n<li>Einordnung der AG Fankulturen aus Sicht der beteiligten Fanorganisationen<\/li>\n<li>Weiterleitung der wesentlichen Diskussionspunkte aus der letzten AG Fankulturen in die Kommission Pr\u00e4vention &amp; Sicherheit &amp; Fu\u00dfballkultur (DFB): u.a. Verbesserung der Hygiene in den Stadien; Umgang mit Sexismus, sexualisierter Bel\u00e4stigung und Gewalt; Erm\u00f6glichung eines geschlechtsunabh\u00e4ngigen Stadionbesuchs insbesondere in Bezug zu Transgender; Kritik an der Einf\u00fchrung der Montagsspiele in der 3.Liga und der fehlenden Ber\u00fccksichtigung von Faninteressen; Kritik am Einsatz des Videoassistenten<\/li>\n<li>Neues aus den Netzwerken: Berichte von den Jahrestreffen der BBAG und von F_in<\/li>\n<li>Dialogabbruch der Fanszenen Deutschlands<\/li>\n<li>Kl\u00e4rung der Rahmenbedingungen f\u00fcr Fallkonferenzen im Rahmen der Pilotphase \u201eFreigabe von Fan-Utensilien\u201d<\/li>\n<li>Stadionverbote:\n<ul>\n<li>Experten aus der ehem. AG Stadionverbote(DFB) berichten \u00fcber Theorie und praktische Umsetzung der Stadionverbotsrichtlinien<\/li>\n<li>Diskussion \u00fcber \u00c4nderungsbedarf bzgl. der Stadionverbotsrichtlinien und insbesondere der Umsetzung der bestehenden Richtlinien mit Experten und Verantwortlichen des DFB<\/li>\n<li>Empfehlung der AG Fankulturen die bestehende Expertise f\u00fcr Evaluations- und Schulungsprozesse beizubehalten und aktiv zu nutzen<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>Wir blicken auf einen intensiven Sitzungstag zur\u00fcck. Eine hohe Bedeutung hat f\u00fcr uns die Einordnung der AG Fankulturen aus Sicht der Fanorganisationen und die Diskussion zum Thema Stadionverbote. Bez\u00fcglich der Stadionverbote werden wir Ende des Jahres berichten k\u00f6nnen, in welcher Form diese Diskussionen beim DFB weitergef\u00fchrt werden.<\/p>\n<p>F\u00fcr weitere Informationen stehen wir gerne zur Verf\u00fcgung.<br \/>\nUnsere Kurve, F_in &#8211; Frauen im Fu\u00dfball, Queer Football Fanclubs<\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Im Rahmen der 9. Sitzung der AG Fankulturen, die am 17. September 2018 stattgefunden hat, wurden folgende Themen diskutiert: Einordnung der AG Fankulturen aus Sicht der beteiligten Fanorganisationen Weiterleitung der wesentlichen Diskussionspunkte aus der letzten AG Fankulturen in die Kommission Pr\u00e4vention &amp; Sicherheit &amp; Fu\u00dfballkultur (DFB): u.a. Verbesserung der Hygiene in den Stadien; Umgang mit&#8230;<\/p>\n","protected":false},"author":4,"featured_media":930,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[36,1],"tags":[],"class_list":["post-614","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ag-fankulturen","category-aktuelles"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>R\u00fcckblick auf 9. Sitzung der AG Fankulturen &#8226; Unsere Kurve<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.unserekurve.de\/blog\/rueckblick-auf-die-9-sitzung-der-ag-fankulturen-am-17-09-2018\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00fcckblick auf 9. Sitzung der AG Fankulturen &#8226; Unsere Kurve\" \/>\n<meta property=\"og:description\" content=\"Im Rahmen der 9. Sitzung der AG Fankulturen, die am 17. September 2018 stattgefunden hat, wurden folgende Themen diskutiert: Einordnung der AG Fankulturen aus Sicht der beteiligten Fanorganisationen Weiterleitung der wesentlichen Diskussionspunkte aus der letzten AG Fankulturen in die Kommission Pr\u00e4vention &amp; Sicherheit &amp; Fu\u00dfballkultur (DFB): u.a. Verbesserung der Hygiene in den Stadien; Umgang mit...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.unserekurve.de\/blog\/rueckblick-auf-die-9-sitzung-der-ag-fankulturen-am-17-09-2018\/\" \/>\n<meta property=\"og:site_name\" content=\"Unsere Kurve\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-18T15:07:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-26T11:57:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.unserekurve.de\/blog\/wp-content\/uploads\/dfl-logo-frankfurt-zentrale.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Robert Pohl\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Robert Pohl\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.unserekurve.de\\\/blog\\\/rueckblick-auf-die-9-sitzung-der-ag-fankulturen-am-17-09-2018\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.unserekurve.de\\\/blog\\\/rueckblick-auf-die-9-sitzung-der-ag-fankulturen-am-17-09-2018\\\/\"},\"author\":{\"name\":\"Robert Pohl\",\"@id\":\"https:\\\/\\\/www.unserekurve.de\\\/blog\\\/#\\\/schema\\\/person\\\/dc7e70ab6b2bb60df11b17fce7ad9704\"},\"headline\":\"R\u00fcckblick auf 9. Sitzung der AG Fankulturen\",\"datePublished\":\"2018-09-18T15:07:02+00:00\",\"dateModified\":\"2020-04-26T11:57:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.unserekurve.de\\\/blog\\\/rueckblick-auf-die-9-sitzung-der-ag-fankulturen-am-17-09-2018\\\/\"},\"wordCount\":259,\"image\":{\"@id\":\"https:\\\/\\\/www.unserekurve.de\\\/blog\\\/rueckblick-auf-die-9-sitzung-der-ag-fankulturen-am-17-09-2018\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.unserekurve.de\\\/blog\\\/wp-content\\\/uploads\\\/dfl-logo-frankfurt-zentrale.jpg\",\"articleSection\":[\"AG Fankulturen\",\"Aktuelles\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.unserekurve.de\\\/blog\\\/rueckblick-auf-die-9-sitzung-der-ag-fankulturen-am-17-09-2018\\\/\",\"url\":\"https:\\\/\\\/www.unserekurve.de\\\/blog\\\/rueckblick-auf-die-9-sitzung-der-ag-fankulturen-am-17-09-2018\\\/\",\"name\":\"R\u00fcckblick auf 9. Sitzung der AG Fankulturen &#8226; Unsere Kurve\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.unserekurve.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.unserekurve.de\\\/blog\\\/rueckblick-auf-die-9-sitzung-der-ag-fankulturen-am-17-09-2018\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.unserekurve.de\\\/blog\\\/rueckblick-auf-die-9-sitzung-der-ag-fankulturen-am-17-09-2018\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.unserekurve.de\\\/blog\\\/wp-content\\\/uploads\\\/dfl-logo-frankfurt-zentrale.jpg\",\"datePublished\":\"2018-09-18T15:07:02+00:00\",\"dateModified\":\"2020-04-26T11:57:48+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.unserekurve.de\\\/blog\\\/#\\\/schema\\\/person\\\/dc7e70ab6b2bb60df11b17fce7ad9704\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.unserekurve.de\\\/blog\\\/rueckblick-auf-die-9-sitzung-der-ag-fankulturen-am-17-09-2018\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.unserekurve.de\\\/blog\\\/rueckblick-auf-die-9-sitzung-der-ag-fankulturen-am-17-09-2018\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.unserekurve.de\\\/blog\\\/rueckblick-auf-die-9-sitzung-der-ag-fankulturen-am-17-09-2018\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.unserekurve.de\\\/blog\\\/wp-content\\\/uploads\\\/dfl-logo-frankfurt-zentrale.jpg\",\"contentUrl\":\"https:\\\/\\\/www.unserekurve.de\\\/blog\\\/wp-content\\\/uploads\\\/dfl-logo-frankfurt-zentrale.jpg\",\"width\":1200,\"height\":533,\"caption\":\"Foto: N. Schipke\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.unserekurve.de\\\/blog\\\/rueckblick-auf-die-9-sitzung-der-ag-fankulturen-am-17-09-2018\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.unserekurve.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R\u00fcckblick auf 9. Sitzung der AG Fankulturen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.unserekurve.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.unserekurve.de\\\/blog\\\/\",\"name\":\"Unsere Kurve\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.unserekurve.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.unserekurve.de\\\/blog\\\/#\\\/schema\\\/person\\\/dc7e70ab6b2bb60df11b17fce7ad9704\",\"name\":\"Robert Pohl\",\"url\":\"https:\\\/\\\/www.unserekurve.de\\\/blog\\\/author\\\/robert\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"R\u00fcckblick auf 9. Sitzung der AG Fankulturen &#8226; Unsere Kurve","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.unserekurve.de\/blog\/rueckblick-auf-die-9-sitzung-der-ag-fankulturen-am-17-09-2018\/","og_locale":"de_DE","og_type":"article","og_title":"R\u00fcckblick auf 9. Sitzung der AG Fankulturen &#8226; Unsere Kurve","og_description":"Im Rahmen der 9. Sitzung der AG Fankulturen, die am 17. September 2018 stattgefunden hat, wurden folgende Themen diskutiert: Einordnung der AG Fankulturen aus Sicht der beteiligten Fanorganisationen Weiterleitung der wesentlichen Diskussionspunkte aus der letzten AG Fankulturen in die Kommission Pr\u00e4vention &amp; Sicherheit &amp; Fu\u00dfballkultur (DFB): u.a. Verbesserung der Hygiene in den Stadien; Umgang mit...","og_url":"https:\/\/www.unserekurve.de\/blog\/rueckblick-auf-die-9-sitzung-der-ag-fankulturen-am-17-09-2018\/","og_site_name":"Unsere Kurve","article_published_time":"2018-09-18T15:07:02+00:00","article_modified_time":"2020-04-26T11:57:48+00:00","og_image":[{"width":1200,"height":533,"url":"https:\/\/www.unserekurve.de\/blog\/wp-content\/uploads\/dfl-logo-frankfurt-zentrale.jpg","type":"image\/jpeg"}],"author":"Robert Pohl","twitter_misc":{"Verfasst von":"Robert Pohl","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.unserekurve.de\/blog\/rueckblick-auf-die-9-sitzung-der-ag-fankulturen-am-17-09-2018\/#article","isPartOf":{"@id":"https:\/\/www.unserekurve.de\/blog\/rueckblick-auf-die-9-sitzung-der-ag-fankulturen-am-17-09-2018\/"},"author":{"name":"Robert Pohl","@id":"https:\/\/www.unserekurve.de\/blog\/#\/schema\/person\/dc7e70ab6b2bb60df11b17fce7ad9704"},"headline":"R\u00fcckblick auf 9. Sitzung der AG Fankulturen","datePublished":"2018-09-18T15:07:02+00:00","dateModified":"2020-04-26T11:57:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.unserekurve.de\/blog\/rueckblick-auf-die-9-sitzung-der-ag-fankulturen-am-17-09-2018\/"},"wordCount":259,"image":{"@id":"https:\/\/www.unserekurve.de\/blog\/rueckblick-auf-die-9-sitzung-der-ag-fankulturen-am-17-09-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/www.unserekurve.de\/blog\/wp-content\/uploads\/dfl-logo-frankfurt-zentrale.jpg","articleSection":["AG Fankulturen","Aktuelles"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.unserekurve.de\/blog\/rueckblick-auf-die-9-sitzung-der-ag-fankulturen-am-17-09-2018\/","url":"https:\/\/www.unserekurve.de\/blog\/rueckblick-auf-die-9-sitzung-der-ag-fankulturen-am-17-09-2018\/","name":"R\u00fcckblick auf 9. Sitzung der AG Fankulturen &#8226; Unsere Kurve","isPartOf":{"@id":"https:\/\/www.unserekurve.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.unserekurve.de\/blog\/rueckblick-auf-die-9-sitzung-der-ag-fankulturen-am-17-09-2018\/#primaryimage"},"image":{"@id":"https:\/\/www.unserekurve.de\/blog\/rueckblick-auf-die-9-sitzung-der-ag-fankulturen-am-17-09-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/www.unserekurve.de\/blog\/wp-content\/uploads\/dfl-logo-frankfurt-zentrale.jpg","datePublished":"2018-09-18T15:07:02+00:00","dateModified":"2020-04-26T11:57:48+00:00","author":{"@id":"https:\/\/www.unserekurve.de\/blog\/#\/schema\/person\/dc7e70ab6b2bb60df11b17fce7ad9704"},"breadcrumb":{"@id":"https:\/\/www.unserekurve.de\/blog\/rueckblick-auf-die-9-sitzung-der-ag-fankulturen-am-17-09-2018\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.unserekurve.de\/blog\/rueckblick-auf-die-9-sitzung-der-ag-fankulturen-am-17-09-2018\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.unserekurve.de\/blog\/rueckblick-auf-die-9-sitzung-der-ag-fankulturen-am-17-09-2018\/#primaryimage","url":"https:\/\/www.unserekurve.de\/blog\/wp-content\/uploads\/dfl-logo-frankfurt-zentrale.jpg","contentUrl":"https:\/\/www.unserekurve.de\/blog\/wp-content\/uploads\/dfl-logo-frankfurt-zentrale.jpg","width":1200,"height":533,"caption":"Foto: N. Schipke"},{"@type":"BreadcrumbList","@id":"https:\/\/www.unserekurve.de\/blog\/rueckblick-auf-die-9-sitzung-der-ag-fankulturen-am-17-09-2018\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.unserekurve.de\/blog\/"},{"@type":"ListItem","position":2,"name":"R\u00fcckblick auf 9. Sitzung der AG Fankulturen"}]},{"@type":"WebSite","@id":"https:\/\/www.unserekurve.de\/blog\/#website","url":"https:\/\/www.unserekurve.de\/blog\/","name":"Unsere Kurve","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.unserekurve.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.unserekurve.de\/blog\/#\/schema\/person\/dc7e70ab6b2bb60df11b17fce7ad9704","name":"Robert Pohl","url":"https:\/\/www.unserekurve.de\/blog\/author\/robert\/"}]}},"jetpack_featured_media_url":"https:\/\/www.unserekurve.de\/blog\/wp-content\/uploads\/dfl-logo-frankfurt-zentrale.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.unserekurve.de\/blog\/wp-json\/wp\/v2\/posts\/614","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unserekurve.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.unserekurve.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.unserekurve.de\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unserekurve.de\/blog\/wp-json\/wp\/v2\/comments?post=614"}],"version-history":[{"count":6,"href":"https:\/\/www.unserekurve.de\/blog\/wp-json\/wp\/v2\/posts\/614\/revisions"}],"predecessor-version":[{"id":1008,"href":"https:\/\/www.unserekurve.de\/blog\/wp-json\/wp\/v2\/posts\/614\/revisions\/1008"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.unserekurve.de\/blog\/wp-json\/wp\/v2\/media\/930"}],"wp:attachment":[{"href":"https:\/\/www.unserekurve.de\/blog\/wp-json\/wp\/v2\/media?parent=614"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.unserekurve.de\/blog\/wp-json\/wp\/v2\/categories?post=614"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.unserekurve.de\/blog\/wp-json\/wp\/v2\/tags?post=614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}